{"id":1247,"date":"2024-06-20T14:30:25","date_gmt":"2024-06-20T12:30:25","guid":{"rendered":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/?p=1247"},"modified":"2025-01-23T10:28:41","modified_gmt":"2025-01-23T09:28:41","slug":"lehramtspraktikum-in-zuerich","status":"publish","type":"post","link":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/2024\/06\/20\/lehramtspraktikum-in-zuerich\/","title":{"rendered":"Lehramtspraktikum in Z\u00fcrich"},"content":{"rendered":"<p>Mein Praktikum an der Schule Limmat begann mit bescheidenen Erwartungen, die sich jedoch schnell in eine faszinierende Erfahrung verwandelten.<\/p>\n<p><!--more--><\/p>\n<p>Die Schulform, welche eine Tagesschule ist, die von der Unterstufe \u00fcber die Mittelstufe bis zur Sekundarschule reicht, fasziniert mich und gab mir einen Einblick in die Struktur einer Tagesschule. Ich war w\u00e4hrend meines Praktikums nur in der Sekundarstufe t\u00e4tig.<\/p>\n<p>Die anf\u00e4ngliche Einteilung nach F\u00e4chern und Jahrg\u00e4ngen erlaubte es mir, in verschiedene Unterrichtseinheiten hineinzuschnuppern und zu hospitieren. Diese Vielseitigkeit gew\u00e4hrte Einblicke in unterschiedliche Lehrmethoden und -ans\u00e4tze. Mentor:innen begleiteten mich durch s\u00e4mtliche Phasen des Unterrichtsprozesses, von der Planung \u00fcber die Durchf\u00fchrung bis zur Reflexion. Mein verantwortlicher Mentor, bei dem ich die meiste Zeit w\u00e4hrend meines Praktikums verbrachte, unterst\u00fctzte mich in allen Phasen und erm\u00f6glichte mir, dass ich mich selbst im Unterricht ausprobieren konnte. Der Schulleiter vermittelte durch seine ausgezeichnete Ausgeglichenheit und offene Pers\u00f6nlichkeit nicht nur ein angenehmes, sondern auch ein \u00e4u\u00dferst unterst\u00fctzendes Arbeitsumfeld, das es dem Team erm\u00f6glichte, in einem respektvollen und f\u00f6rderlichen Raum zusammenzuarbeiten.<\/p>\n<p>Die Erkenntnis, dass kleinere Klassen (18-23 Sch\u00fcler:innen) das Unterrichten an der Schule Limmat vereinfachen und eine angenehme Lernatmosph\u00e4re schaffen, vertiefte sich w\u00e4hrend meines Praktikums. Die freundliche Art sowohl der Sch\u00fcler:innen als auch der Lehrkr\u00e4fte trug dazu bei, dass der Unterricht nicht nur effektiv, sondern auch angenehm gestaltet werden konnte. Die Herausforderung, das Praktikum mit Online-Sitzungen, Universit\u00e4tsseminaren und weiteren Aufgaben in Einklang zu bringen, war konstant pr\u00e4sent.<\/p>\n<p>Dennoch sorgten die Offenheit meiner Kolleg:innen und das gem\u00e4chliche Leben in einer Stadt wie Z\u00fcrich f\u00fcr eine ausgewogene Balance. Besonders pr\u00e4gend war die Klassenfahrt und der Schneetag, bei denen ich die Sch\u00fcler:innen als auch meine Kolleg:innen besser kennenlernen konnte. Daraus entwickelten sich auch andere Gespr\u00e4che und es kam zu einem pers\u00f6nlichen Austausch.<br \/>\nEinladungen zu Geburtstagen und anderen sozialen Aktivit\u00e4ten seitens der Lehrkr\u00e4fte f\u00fchrten zu einem tieferen Verst\u00e4ndnis f\u00fcr die lokale Kultur und dauerhaften Freundschaften.<\/p>\n<p>Insgesamt war mein Praktikum an der Schule Limmat eine reiche Erfahrung, die nicht nur meine p\u00e4dagogischen F\u00e4higkeiten vertiefte, sondern auch einen nachhaltigen Eindruck von der Schullandschaft der Schweiz hinterlie\u00df. Die Kombination aus fachlicher Entwicklung und pers\u00f6nlichem Austausch pr\u00e4gte meine Zeit an der Schule nachhaltig. Ich kann Lehramtsstudierenden w\u00e4rmstens empfehlen, ein Praktikum an der Schule Limmat in Z\u00fcrich zu absolvieren, da die gewonnenen Eindr\u00fccke \u00e4u\u00dferst bereichernd waren. W\u00e4hrend meines Aufenthalts stellte ich fest, dass sowohl f\u00fcr Lehrkr\u00e4fte als auch f\u00fcr Sch\u00fcler:innen das regelm\u00e4\u00dfige Aufhalten im Freien sehr positiv war. Das \u00fcberwiegend gute Wetter (Herbst plus Winter) erm\u00f6glichte viel Zeit auf dem Pausenhof, am Nachmittag am Fluss Limmat oder am Wochenende in den nahe liegenden Bergen, was zu einer insgesamt entspannten Atmosph\u00e4re unter den Kolleg:innen und Sch\u00fcler:innen f\u00fchrte.<\/p>\n<p>Es ist von besonderer Wichtigkeit zu unterstreichen, dass dieses Praktikum eine herausragende Gelegenheit darstellte, meine berufliche Weiterentwicklung ma\u00dfgeblich zu f\u00f6rdern, gleichzeitig aber auch Raum f\u00fcr das Sammeln neuer Erkenntnisse sowie das Kn\u00fcpfen wertvoller Kontakte bot.<br \/>\nDie Teilnahme an diesem Praktikum erm\u00f6glichte mir nicht nur, meine fachlichen Kompetenzen zu vertiefen, sondern er\u00f6ffnete auch die M\u00f6glichkeit, in einem beruflichen Umfeld aktiv zu agieren und praxisorientierte Einblicke zu gewinnen. Dar\u00fcber hinaus bot sich die Chance, mit verschiedenen Pers\u00f6nlichkeiten in Kontakt zu treten und von deren Erfahrungen zu profitieren, was nicht nur meinen beruflichen Horizont erweiterte, sondern auch meine sozialen F\u00e4higkeiten bereicherte.<\/p>\n<p>Insgesamt erwies sich dieses Praktikum als eine \u00e4u\u00dferst bedeutsame Etappe meiner beruflichen Entwicklung, die nicht nur meine Fachkenntnisse vertiefte, sondern auch zu einem tieferen Verst\u00e4ndnis f\u00fcr die Anforderungen und Dynamiken des Arbeitslebens beitrug. Die erlangten Erfahrungen w\u00e4hrend dieses Praktikums trugen dazu bei, meine beruflichen Perspektiven zu kl\u00e4ren und meine berufliche Identit\u00e4t zu st\u00e4rken. Insbesondere die M\u00f6glichkeit, in einem realen beruflichen Umfeld zu agieren, verschaffte mir wertvolle Einblicke, die \u00fcber die theoretischen Aspekte meiner Ausbildung hinausgingen.<br \/>\nAlles in allem war es eine gro\u00dfartige Erfahrung, f\u00fcr die ich sehr dankbar bin und die mich noch lange gl\u00fccklich zur\u00fcckdenken l\u00e4sst.<\/p>\n<hr \/>\n<p><strong>Tipps f\u00fcr andere Praktikant:innen<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Vorbereitung<\/strong><\/p>\n<p>Ich habe intensiv recherchiert, um mich mit der Stadt, in der ich wohnen werde, vertraut zu machen. Dabei habe ich mir viele Schule erstmal online angeschaut. W\u00e4hrend der Semesterferien (zwischen Wintersemester 2022\/23 und dem Sommersemester 2023) reiste ich nach Z\u00fcrich und hatte f\u00fcnf Bewerbungsgespr\u00e4che, an denen ich die Schulleitungen sowie meine m\u00f6glichen Mentor:innen kennenlernen konnte. Nach ausf\u00fchrlichen Gespr\u00e4chen und Austausch mit Freund:innen wie Kommiliton:innen entschied ich mich f\u00fcr die Schule Limmat.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Beantragung Visum<\/strong><\/p>\n<p>EU-B\u00fcrger oder Personen mit einem g\u00fcltigen EU-Aufenthaltstitel ben\u00f6tigen kein Visum.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Praktikumssuche<\/strong><\/p>\n<p>Die Praktikumssuche dauerte bei mir \u00fcber zwei Monate, da ich mir die Schulen genaustens aussehen wollte. Es g\u00e4be auch die M\u00f6glichkeit, \u00fcber die Websites der Schulen Informationen zu bekommen.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Wohnungssuche<\/strong><\/p>\n<p>Ich habe f\u00fcr die Zeit (01.09.2023 \u2013 31.01.2024) in einer Wohnung gewohnt. Ich hatte bei der Wohnungssuche Gl\u00fcck, da eine Freundin von mir, die Person kannte. Die Person reiste nach Asien\/ Australien in dem Zeitraum, wo ich in Z\u00fcrich war, sodass es einen reibungslosen \u00dcbergang mit der Wohnung gab. Ich w\u00fcrde Personen jedoch empfehlen, eventuell in eine Wohngemeinschaft zu ziehen, da ich gemerkt habe, dass allein wohnen in einer fremden Stadt auch manchmal \u201eeinsam\u201c ist.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Versicherung<\/strong><\/p>\n<p>Die TK Krankenkasse bietet spezielle Versicherungspakete f\u00fcr junge Menschen an, die Praktika oder Auslandssemester absolvieren. Zudem gibt es kosteng\u00fcnstige Alternativen bei der Haftpflichtkasse. Ich habe das Paket der AXA-Versicherung gew\u00e4hlt.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Sonstiges<\/strong><\/p>\n<p>Z\u00fcrich hat einen gut funktionierenden \u00d6ffentlichen Nahverkehr. Zudem bietet die Stadt viele M\u00f6glichkeiten zum kulturellen Vergn\u00fcgen. Au\u00dferdem hat Z\u00fcrich eine hohe Lebensqualit\u00e4t, da man \u00fcberall freien Zugang und \u00f6ffentliche Badeanstalten am Fluss sowie am See hat. Zudem erreicht man von Z\u00fcrich andere St\u00e4dte wie St. Gallen oder Bern mit dem Zug innerhalb von einer Stunde, sodass man am Wochenende auch die anderen Teile der Schweiz besuchen kann.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><em><strong>Formalit\u00e4ten vor Ort<\/strong><\/em><\/p>\n<p><strong>Telefon-\/Internetanschluss<\/strong><\/p>\n<p>Ich habe mir eine Schweizer Sim-Karte f\u00fcr den Zeitraum zugelegt, welche ca. 40 Euro pro Monat gekostet hat, da Schweiz nicht in der EU ist und somit die mobilen Daten sowie die anderen Dienste mit einer deutschen Nummer sehr teuer w\u00e4ren. W-Lan besa\u00df ich in der Wohnung, in der ich wohnte. Es kostet auch ungef\u00e4hr 40 Euro, damit man eine gut funktionierende Verbindung besitzt.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Bank\/Kontoer\u00f6ffnung<\/strong><\/p>\n<p>Es war nicht notwendig, ein Bankkonto zu er\u00f6ffnen, da deutsche Giro- und Kreditkarten problemlos genutzt werden konnten. Einige Automaten berechneten zwar Geb\u00fchren, diese betrugen jedoch h\u00f6chstens etwa 3 Euro. Zudem war es an vielen Orten m\u00f6glich, mit der Karte zu bezahlen.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Sonstiges<\/strong><\/p>\n<p>Ich muss gestehen, dass ich \u00fcberall auf entspannte und sehr freundliche Menschen traf. Aufgrund dessen, dass sich Z\u00fcrich im deutschsprachigen Teil der Schweiz befindet, gab es auch dort keine Probleme.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><em><strong>Alltag\/Freizeit<\/strong><\/em><\/p>\n<p><strong>Ausgehm\u00f6glichkeiten<\/strong><\/p>\n<p>Es gibt in Z\u00fcrich viele Ausgehm\u00f6glichkeiten, ob Bars, Clubs oder andere Einrichtungen wie Museen oder Theaters.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Sonstiges<\/strong><\/p>\n<p>Wenn man sich erst einmal an das entschleunigte Leben gew\u00f6hnt hat, wird man die Zeit in Z\u00fcrich sehr sch\u00e4tzen und genie\u00dfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mein Praktikum an der Schule Limmat begann mit bescheidenen Erwartungen, die sich jedoch schnell in eine faszinierende Erfahrung verwandelten.<\/p>\n","protected":false},"author":3982,"featured_media":1248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[486393],"tags":[34269,918,486523],"class_list":["post-1247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-praktikum-europa","tag-lehramt","tag-schweiz","tag-zuerich"],"_links":{"self":[{"href":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/wp-json\/wp\/v2\/posts\/1247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/wp-json\/wp\/v2\/users\/3982"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/wp-json\/wp\/v2\/comments?post=1247"}],"version-history":[{"count":1,"href":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/wp-json\/wp\/v2\/posts\/1247\/revisions"}],"predecessor-version":[{"id":1249,"href":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/wp-json\/wp\/v2\/posts\/1247\/revisions\/1249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/wp-json\/wp\/v2\/media\/1248"}],"wp:attachment":[{"href":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/wp-json\/wp\/v2\/media?parent=1247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/wp-json\/wp\/v2\/categories?post=1247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.fu-berlin.de\/auslandspraktikum\/wp-json\/wp\/v2\/tags?post=1247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}