{"id":1030,"date":"2025-12-17T11:28:11","date_gmt":"2025-12-17T11:28:11","guid":{"rendered":"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/?p=1030"},"modified":"2025-12-17T11:28:11","modified_gmt":"2025-12-17T11:28:11","slug":"estagio-em-mocambique","status":"publish","type":"post","link":"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/2025\/12\/17\/estagio-em-mocambique\/","title":{"rendered":"Est\u00e1gio em Mo\u00e7ambique"},"content":{"rendered":"\n<p>O projeto de interc\u00e2mbio, que visava apoiar educadores em Mo\u00e7ambique na cria\u00e7\u00e3o de materiais de aprendizagem inclusivos e contextualizados para as primeiras classes do ensino prim\u00e1rio (primeira a quarta classe), teve in\u00edcio em Leipzig, na Alemanha, com aulas sobre did\u00e1ticas e oficinas pedag\u00f3gicas. A segunda e principal fase ocorreu em Mo\u00e7ambique, iniciando-se em Maputo, para organiza\u00e7\u00e3o inicial do projeto ASA (focado na implementa\u00e7\u00e3o de uma <em>Lernwerkstatt, <\/em>ou Oficina Pedag\u00f3gica) e estabelecimento de contatos na Universidade Pedag\u00f3gica.<\/p>\n\n\n\n<p>A chegada em Nampula marcou o in\u00edcio dos trabalhos na Universidade Rovuma (Uni Rovuma), o ambiente de trabalho pelos tr\u00eas meses seguintes. Foi crucial a participa\u00e7\u00e3o no Simp\u00f3sio Brasil &#8211; Mo\u00e7ambique, onde foi estabelecido contato com Christiane Maia, l\u00edder do projeto &#8222;Ubuntu Educacional&#8220;, que ofereceu grande apoio e confirmou o estranhamento inicial percebido em rela\u00e7\u00e3o \u00e0 cultura local.<\/p>\n\n\n\n<p>Os desafios estruturais e culturais em Mo\u00e7ambique foram imediatos. Estranhamentos iniciais inclu\u00edram a associa\u00e7\u00e3o negativa de livros aos colonizadores portugueses, ligada ao fato de l\u00ednguas nativas como o <em>Xichangana <\/em>e o <em>emakhuwa <\/em>serem majoritariamente faladas, n\u00e3o escritas. O ambiente institucional era marcado por hierarquias e formalidades paternalistas, como o costume de todos se levantarem na presen\u00e7a do vice-reitor, e um c\u00f3digo de vestimenta estritamente formal, mesmo com o calor. A Uni Rovuma apresentava dificuldades como a falta de acesso \u00e0 internet, atraso no sal\u00e1rio dos trabalhadores e insufici\u00eancia de salas de aula e energia.<\/p>\n\n\n\n<p>O projeto enfrentou desafios conceituais e log\u00edsticos. A tradu\u00e7\u00e3o de <em>Lernwerkstatt <\/em>para &#8222;Oficina Pedag\u00f3gica&#8220; foi considerada inadequada. Logicamente, o espa\u00e7o designado inicialmente, a sala QueProF, era inadequado por ser multiuso e ter acesso restrito. Houve tamb\u00e9m a necessidade de solicitar materiais recicl\u00e1veis para a produ\u00e7\u00e3o dos jogos, visto que n\u00e3o foi poss\u00edvel obter financiamento direto da Alemanha. O financiamento do projeto ASA tamb\u00e9m levantou questionamentos, pois foi observado que ele tende a dificultar a circula\u00e7\u00e3o de conhecimento entre \u00c1frica e Europa, beneficiando predominantemente o Norte Global.<\/p>\n\n\n\n<p>As V Jornadas Cient\u00edficas da Uni Rovuma foram importantes, permitindo \u00e0 pesquisadora apresentar seu trabalho e, apesar da falta de energia, propor uma mesa redonda com \u00f3rg\u00e3os pedag\u00f3gicos. As visitas de observa\u00e7\u00e3o em 4 escolas, essenciais para o projeto, revelaram uma profunda desigualdade educacional em Nampula. O CREI \u2013 Centro de Recursos de Educa\u00e7\u00e3o Inclusiva Josina Machel serviu como uma refer\u00eancia positiva, com salas organizadas, uso de L\u00edngua de Sinais (LIBRAS) e materiais did\u00e1ticos concretos e apropriados, refor\u00e7ando a necessidade do projeto focar em materiais inclusivos.<\/p>\n\n\n\n<p>A fase final do projeto concentrou-se no envolvimento dos estudantes de Pedagogia da Uni Rovuma, que participaram em indu\u00e7\u00f5es e come\u00e7aram a produ\u00e7\u00e3o pr\u00e1tica de materiais. Foram elaborados cerca de 15 materiais para Portugu\u00eas e 15 para Matem\u00e1tica, incluindo o Jogo de Mem\u00f3ria Alfabeto. O trabalho culminou na Exposi\u00e7\u00e3o de Materiais Did\u00e1tico-Pedag\u00f3gicos e na instala\u00e7\u00e3o provis\u00f3ria dos materiais na sala QueProF, com a sugest\u00e3o de criar um cat\u00e1logo para empr\u00e9stimo.<\/p>\n\n\n\n<p>A experi\u00eancia foi considerada inspiradora, permitindo perceber a forte presen\u00e7a cultural de Mo\u00e7ambique no Brasil. Apesar das dificuldades de infraestrutura, barreiras lingu\u00edsticas (entre o sotaque pernambucano, portugu\u00eas de Portugal e portugu\u00eas mo\u00e7ambicano) e o peso do senso cr\u00edtico em rela\u00e7\u00e3o \u00e0 &#8222;branquitude&#8220; da pesquisadora, o projeto se mostrou bonito e necess\u00e1rio. As observa\u00e7\u00f5es de 50 a 120 crian\u00e7as sentadas no ch\u00e3o ansiando por aprender ilustraram a natureza primordial dos desafios. Para futuras edi\u00e7\u00f5es, a pesquisadora ressalta a import\u00e2ncia da participa\u00e7\u00e3o estudantil, da tradu\u00e7\u00e3o dos materiais para l\u00ednguas locais como o Emakhuwa, e de um planejamento pr\u00e9vio mais robusto e com recursos.<\/p>\n\n\n\n<p>Autora: St\u00e9phanie Gueiros de Medeiros Lopes (2025)<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O projeto de interc\u00e2mbio, que visava apoiar educadores em Mo\u00e7ambique na cria\u00e7\u00e3o de materiais de aprendizagem inclusivos e contextualizados para as primeiras classes do ensino prim\u00e1rio (primeira a quarta classe), teve in\u00edcio em Leipzig, na Alemanha, com aulas sobre did\u00e1ticas e oficinas pedag\u00f3gicas. A segunda e principal fase ocorreu em Mo\u00e7ambique, iniciando-se em Maputo, para &hellip; <a href=\"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/2025\/12\/17\/estagio-em-mocambique\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eEst\u00e1gio em Mo\u00e7ambique\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1659,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[587663],"tags":[],"class_list":["post-1030","post","type-post","status-publish","format-standard","hentry","category-1-3-praktikumsberichte"],"_links":{"self":[{"href":"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/wp-json\/wp\/v2\/posts\/1030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/wp-json\/wp\/v2\/users\/1659"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/wp-json\/wp\/v2\/comments?post=1030"}],"version-history":[{"count":1,"href":"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/wp-json\/wp\/v2\/posts\/1030\/revisions"}],"predecessor-version":[{"id":1031,"href":"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/wp-json\/wp\/v2\/posts\/1030\/revisions\/1031"}],"wp:attachment":[{"href":"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/wp-json\/wp\/v2\/media?parent=1030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/wp-json\/wp\/v2\/categories?post=1030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.fu-berlin.de\/wissenschaftspraxis-lai\/wp-json\/wp\/v2\/tags?post=1030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}